{"id":639,"date":"2023-02-14T08:55:22","date_gmt":"2023-02-14T08:55:22","guid":{"rendered":"https:\/\/ronson.com.my\/?page_id=639"},"modified":"2023-02-22T03:50:24","modified_gmt":"2023-02-22T03:50:24","slug":"project-photos","status":"publish","type":"page","link":"https:\/\/ronson.com.my\/index.php\/project-photos\/","title":{"rendered":"Project Photos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"639\" class=\"elementor elementor-639\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-63819ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"63819ca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ceedae0\" data-id=\"ceedae0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9e7d5f elementor-arrows-position-inside elementor-pagination-position-outside elementor-invisible elementor-widget elementor-widget-image-carousel\" data-id=\"e9e7d5f\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;2&quot;,&quot;slides_to_scroll&quot;:&quot;2&quot;,&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.9.0 - 06-12-2022 *\/\n.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ronson.com.my\/wp-content\/uploads\/2023\/02\/Sec.-4J-Project-Photo-Goldis_page-0003-791x1024.jpg\" alt=\"Sec. 4J -Project Photo (Goldis)_page-0003\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ronson.com.my\/wp-content\/uploads\/2023\/02\/Sec.-4J-Project-Photo-Goldis_page-0002-791x1024.jpg\" alt=\"Sec. 4J -Project Photo (Goldis)_page-0002\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ronson.com.my\/wp-content\/uploads\/2023\/02\/Sec.-4J-Project-Photo-Goldis_page-0001-791x1024.jpg\" alt=\"Sec. 4J -Project Photo (Goldis)_page-0001\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ronson.com.my\/wp-content\/uploads\/2023\/02\/Sec.-4I-Project-Photo-Verdana_page-0001-791x1024.jpg\" alt=\"Sec. 4I -Project Photo (Verdana)_page-0001\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ronson.com.my\/wp-content\/uploads\/2023\/02\/Sec.-4G-Project-Photo-Bellworth_page-0001-791x1024.jpg\" alt=\"Sec. 4G -Project Photo (Bellworth)_page-0001\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ronson.com.my\/wp-content\/uploads\/2023\/02\/Sec.-4E2-Project-Photo-BSC_page-0002-791x1024.jpg\" alt=\"Sec. 4E2 -Project Photo (BSC)_page-0002\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ronson.com.my\/wp-content\/uploads\/2023\/02\/Sec.-4E2-Project-Photo-BSC_page-0001-791x1024.jpg\" alt=\"Sec. 4E2 -Project Photo (BSC)_page-0001\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ronson.com.my\/wp-content\/uploads\/2023\/02\/Sec.-4D-Project-Photo-Stonor-3_page-0001-724x1024.jpg\" alt=\"Sec. 4D -Project Photo (Stonor 3)_page-0001\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ronson.com.my\/wp-content\/uploads\/2023\/02\/Sec.-4H-Project-Photo-Amphil.jpg\" alt=\"Sec. 4H -Project Photo (Amphil)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Previous Next<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"_links":{"self":[{"href":"https:\/\/ronson.com.my\/index.php\/wp-json\/wp\/v2\/pages\/639"}],"collection":[{"href":"https:\/\/ronson.com.my\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ronson.com.my\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ronson.com.my\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ronson.com.my\/index.php\/wp-json\/wp\/v2\/comments?post=639"}],"version-history":[{"count":10,"href":"https:\/\/ronson.com.my\/index.php\/wp-json\/wp\/v2\/pages\/639\/revisions"}],"predecessor-version":[{"id":707,"href":"https:\/\/ronson.com.my\/index.php\/wp-json\/wp\/v2\/pages\/639\/revisions\/707"}],"wp:attachment":[{"href":"https:\/\/ronson.com.my\/index.php\/wp-json\/wp\/v2\/media?parent=639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}